{"id":617,"count":15640,"description":"","link":"https:\/\/stevebenen.com\/thecarpetbaggerreport\/category\/general\/","name":"General","slug":"general","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/stevebenen.com\/thecarpetbaggerreport\/wp-json\/wp\/v2\/categories\/617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/stevebenen.com\/thecarpetbaggerreport\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/stevebenen.com\/thecarpetbaggerreport\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/stevebenen.com\/thecarpetbaggerreport\/wp-json\/wp\/v2\/posts?categories=617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}